{"id":8254,"date":"2022-08-26T19:10:30","date_gmt":"2022-08-26T19:10:30","guid":{"rendered":"https:\/\/dicopebisuteria.com\/tienda\/?page_id=8254"},"modified":"2025-08-14T08:27:52","modified_gmt":"2025-08-14T08:27:52","slug":"preguntas-frecuentes","status":"publish","type":"page","link":"https:\/\/dicopebisuteria.com\/tienda\/preguntas-frecuentes\/","title":{"rendered":"PREGUNTAS FRECUENTES"},"content":{"rendered":"<p>&nbsp;<\/p>\n<h1 style=\"text-align: center;\">PREGUNTAS FRECUENTES<\/h1>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: center;\">Bienvenida a Dicope Bisuter\u00eda Preciosa!<\/h3>\n<p style=\"text-align: center;\">Encuentra <strong>Bisuter\u00eda Artesanal<\/strong> creada personalmente en mi taller de Barcelona<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\">\u00a0INFORMACION<\/h2>\n<h4 style=\"text-align: center;\"><a href=\"https:\/\/dicopebisuteria.com\/tienda\/mi-cuenta\/\"><strong>MI CUENTA \/ LOG IN<\/strong><\/a><strong><br \/>\n<a href=\"https:\/\/dicopebisuteria.com\/tienda\/gastos-de-envio\/\">GASTOS DE ENVIO<\/a><br \/>\n<\/strong><a href=\"https:\/\/dicopebisuteria.com\/tienda\/metodos-de-pago\/\"><strong>METODOS DE PAGO<\/strong><\/a><strong><br \/>\n<a href=\"https:\/\/dicopebisuteria.com\/tienda\/cambios-y-devoluciones\/\">Cambios y devoluciones<\/a><\/strong><a href=\"https:\/\/dicopebisuteria.com\/tienda\/preguntas-frecuentes\/\"><strong><br \/>\nPreguntas Frecuentes<\/strong><\/a><strong><br \/>\n<a href=\"http:\/\/dicopebisuteria.com\/tienda\/contacto\/\">CONTACTO<\/a><\/strong><\/h4>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: center;\">OTRAS PREGUNTAS<\/h3>\n<p>[vc_toggle title=\u00bbCOMO COMPRAR\u00bb]<strong>Como comprar en la web tienda? <\/strong>Es muy f\u00e1cil! Solo tienes que a\u00f1adir las piezas que te gusten en el carrito de compra (Fijandote si quieres alguna medida concreta de cada joyita) y seguir los pasos para rellenar tus datos y pagar tu pedido \ud83d\ude0d<strong><br \/>\n<\/strong><\/p>\n<p><strong>Como puedo pagar?<\/strong> Puedes pagar con <strong>paypal<\/strong>, con <strong>bizum , <\/strong>con<strong> transferencia bancaria<\/strong> o <strong>contra reembolso<\/strong> Mas info de como funciona cada m\u00e9todo de pago aqu\u00ed &gt;&gt;&gt; <a href=\"https:\/\/dicopebisuteria.com\/tienda\/metodos-de-pago\/\">https:\/\/dicopebisuteria.com\/tienda\/metodos-de-pago\/<\/a><\/p>\n<p><strong>Necesito registrarme o crear una cuenta para comprar?<\/strong> No hace falta! Aunque yo te lo recomiendo para que te sea mas f\u00e1cil pedir de nuevo ;)<\/p>\n<p><strong>Que hago si tengo alg\u00fan problema y no me deja comprar??<\/strong> Si tienes problemas durante el proceso de compra m\u00e1ndame un chat de <strong> Whatsapp 638890244<\/strong> o contactame por correo a dicopebisuteriashop @ gmail .com <strong>(sin espacios)<\/strong><\/p>\n<p><strong>Ofreces alg\u00fan Descuento?<\/strong> Si! tienes un 20% de descuento si te unes a mi lista secreta (newsletter) &gt;&gt; <a href=\"http:\/\/eepurl.com\/dyKvor\">http:\/\/eepurl.com\/dyKvor<\/a>[\/vc_toggle][\/vc_column][\/vc_row][vc_row][vc_column][vc_toggle title=\u00bbPEDIDOS &amp; ENVIOS\u00bb]<strong>Cuando tardas en Enviar mi Pedido?<\/strong> Puedo tardar uno o dos d\u00edas, si pides tu pedido en Viernes ser\u00e1 enviado el siguiente Lunes<\/p>\n<p><strong>A donde Env\u00edas Pedidos?<\/strong> Hago env\u00edos a todo el mundo! Puedes hacer tu pedido desde la web en espa\u00f1ol (esta) o desde la web en ingles &gt;&gt; <a href=\"https:\/\/dicopebisuteria.com\/shop\">https:\/\/dicopebisuteria.com\/shop<\/a><\/p>\n<p><strong>Cuando tarda en llegarme mi Pedido?<\/strong> En Espa\u00f1a tu pedido puede tardar unos 3 o 4 d\u00edas laborables, ten en cuenta que si pides en viernes tu pedido se enviar\u00e1 el siguiente lunes! En Europa tu pedido puede tardar unos 6 a 8 d\u00edas laborables y en el resto del mundo de 20 a 30 d\u00edas ;)<\/p>\n<p><strong>Cuanto valen los gastos de envio?<\/strong> Si vives en Espa\u00f1a son 4,9 euros y 12 si lo quieres urgente , para el resto de pa\u00edses son 12 euros<\/p>\n<p><strong>Desde donde Env\u00edas los pedidos?<\/strong> Desde la ciudad de Barcelona en Espa\u00f1a<\/p>\n<p><strong>Podemos quedar en persona si vivo en Barcelona?<\/strong> Si quieres podemos quedar en persona , solo para pedidos de 40 euros o mas, m\u00e1ndame un chat de <strong> Whatsapp al 638890244<\/strong> y quedamos ;)<\/p>\n<p><strong>Como puedo hacer el seguimiento de mi pedido?<\/strong> Te enviare a tu email el numero de seguimiento y podr\u00e1s seguirlo en la web de correos Espa\u00f1a ;)<\/p>\n<p><strong>Que contiene el paquete que me env\u00edas??<\/strong> Tu pedido vendr\u00e1 seguramente en un sobre peque\u00f1o con tus joyitas y una cajita de regalo y algunas de mis pegatinas, normalmente no incluyo el tiquet de compra<\/p>\n<p><strong>Tendr\u00e9 que pagar algo de Aduanas o otras Tasas?<\/strong> Si vives en Espa\u00f1a no tendr\u00e1s que pagar nada , excepto las islas canarias donde si te pueden hacer pagar algo! Si pides de fuera de la uni\u00f3n Europea , puede ser que tengas que pagar algo de impuestos de Aduanas, pero eso ya depende de cada pa\u00eds<\/p>\n<p><strong>Que hago si NO me llega el pedido en el tiempo que me has indicado o se retrasa??<\/strong> Puedes contactarme inmediatamente para que pueda ver como esta tu pedido y decirte lo que se puede hacer ;) m\u00e1ndame un chat de <strong> Whatsapp 638890244<\/strong> o contactame por correo a dicopebisuteriashop @ gmail .com <strong>(sin espacios)<\/strong>[\/vc_toggle][\/vc_column][\/vc_row][vc_row][vc_column][vc_toggle title=\u00bbPROBLEMAS &amp; DEVOLUCIONES\u00bb]<strong>Puedo devolver o cambiar mi Joya?<\/strong> Si! Puedes devolver o cambiar tu joya, tienes hasta 60 d\u00edas despues de recibir tu pedido ;)<\/p>\n<p><strong>Como funciona una devoluci\u00f3n?<\/strong> Si quieres devolver tu joyita , primero ponte en contacto conmigo por email al\u00a0 dicopebisuteriashop @ gmail .com (sin espacios) para la devoluci\u00f3n deberas devolverme la joyita por correo (tu pagaras ese env\u00edo) cuando me llegue la joyita te devolver\u00e9 el dinero, descontando los 4,9 euros del primer env\u00edo<\/p>\n<p><strong>Cuando tardas en abonarme mi dinero?<\/strong> Te enviare tu dinero , tras recibir la joyita en buen estado, lo recibir\u00e1s esa misma semana<\/p>\n<p><strong>Cuanto me cuesta una devoluci\u00f3n?<\/strong> En una devoluci\u00f3n tu pagas por enviarme la joyita de vuelta y tambi\u00e9n se descuenta el precio del primer env\u00edo (4,9 euros) as\u00ed que lo mas seguro es que te cueste entre 5 y 12 euros en total<\/p>\n<p><strong>Como funciona un cambio de joyita por otra?<\/strong> Si tu joyita no te gusta y la quieres cambiar por otra, primero ponte en contacto conmigo por email al\u00a0 dicopebisuteriashop @ gmail .com (sin espacios) deberas mandarme la joyita , tu pagaras por enviarmela de vuelta y deberas pagar tambi\u00e9n el precio de env\u00edo de la siguiente joyita (4,9 euros en Espa\u00f1a o 12 en pedidos internacionales)<\/p>\n<p><strong>Cuando tardas en enviarme una nueva joyita en un cambio?<\/strong> te la mandare esa misma semana, despu\u00e9s de recibir la otra joyita y el dinero del env\u00edo ;)<\/p>\n<p><strong>Que pasa si mi pedido NO llega y parece Perdido?<\/strong> Si tu pedido tarda mas del tiempo indicado podr\u00eda estar perdido, normalmente te recomiendo esperar una semana mas en Espa\u00f1a, dos en Europa y tres en el resto del mundo. Pero si crees que tu pedido tarda demasiado en llegar contactame enseguida y veremos que se puede hacer ;) Te en cuenta que los pedidos no se consideran oficialmente perdidos hasta 8 semanas despues de enviarlos!<\/p>\n<p><strong>Cuando tardas en abonarme mi dinero o mandarme otra vez mis joyitas en pedido perdidos? <\/strong>Si ya han pasado 8 semanas y no sabes nada de tu pedido (4 semanas solo para Espa\u00f1a) podr\u00e1s elegir si quieres que te lo mande de nuevo o te reembolse tu dinero<strong><br \/>\n<\/strong><\/p>\n<p><strong>Que pasa si he escogido mal mi talla? <\/strong>Si tu joyita no es tu talla y la quieres cambiar por otra, primero ponte en contacto conmigo por email al\u00a0 dicopebisuteriashop @ gmail .com (sin espacios) deberas mandarme la joyita , tu pagaras por enviarmela de vuelta y deberas pagar tambi\u00e9n el precio de env\u00edo de la siguiente joyita (4 euros en Espa\u00f1a o 8 en pedidos internacionales) Es importante que midas bien tu talla\u00a0 para no volverte a equivocar &gt;&gt; <a href=\"https:\/\/dicopebisuteria.com\/tienda\/como-elegir-tallas-de-joyas\/\">https:\/\/dicopebisuteria.com\/tienda\/como-elegir-tallas-de-joyas\/<\/a><strong><br \/>\n<\/strong><\/p>\n<p><strong>Y si el error de talla a sido tuyo y no mio?<\/strong> No te preocupes, m\u00e1ndame la joyita de vuelta y si realmente no era la medida que deb\u00eda ser porsupuesto que no te cobrare nada para cambiartela <strong>\ud83d\ude0d<br \/>\n<\/strong><\/p>\n<p><strong>Que pasa si mi paquete llega en mal estado?<\/strong> Si tu paquete llega en mal estado pide al cartero que te haga un informe de da\u00f1os , tambi\u00e9n ten en cuenta hacerle fotos antes de abrirlo ! Si la pieza tambi\u00e9n esta rota yo me har\u00e9 cargo y te lo cambiar\u00e9 por otra pieza sin coste alguno ! Solo valido durante los primeros 4 d\u00edas despues de recibir tu paquete! Contactame enseguida para poder resolverlo ;)<\/p>\n<p><strong>Que pasa si el paquete parece que esta bien, pero dentro la joya esta rota?<\/strong> Si tu paquete parec\u00eda que estaba bien pero la pieza te llega rota , contactame inmediatamente con fotos claras del problema y yo te lo cambiar\u00e9 por otra pieza sin coste alguno ! Solo valido durante los primeros 4 d\u00edas despues de recibir tu paquete!<\/p>\n<p><strong>Se pueden devolver las joyitas personalizadas?<\/strong> Los pedidos personalizados NO se pueden devolver! Pero no te preocupes, te mandar\u00e9 muchas fotos antes de envi\u00e1rtelo para que est\u00e9s segura de tu compra ;)<\/p>\n<p><strong>Que pasa si mi joyita se me rompe a los pocos d\u00edas?<\/strong> Si tu compra de bisuter\u00eda artesanal se te rompe en pocos d\u00edas env\u00edame fotos enseguida por email y yo te dir\u00e9 si se puede arreglar y el coste!<\/p>\n<p><strong>Que pasa si mi joyita se pone fea con el tiempo? <\/strong>Puedes encontrar consejos de como cuidar tus joyitas aqu\u00ed &gt;&gt; <a href=\"https:\/\/dicopebisuteria.com\/tienda\/como-cuidar-tus-joyitas\/\">https:\/\/dicopebisuteria.com\/tienda\/como-cuidar-tus-joyitas\/<\/a><\/p>\n<p>Pero si ya se te ha puesto fea , contactame y veremos que se puede hacer<strong><br \/>\n<\/strong>[\/vc_toggle][\/vc_column][\/vc_row][vc_row][vc_column][vc_toggle title=\u00bbPRODUCTOS\u00bb]<strong>Como puedo medir la Talla de mi anillo?<\/strong> Puedes ver las tallas de anillos y como medirlas aqui &gt;&gt; <a href=\"https:\/\/dicopebisuteria.com\/tienda\/como-elegir-tallas-de-joyas\/\">https:\/\/dicopebisuteria.com\/tienda\/como-elegir-tallas-de-joyas\/<\/a><\/p>\n<p><strong>Como puedo medir la Talla de mi pulsera o collar?<\/strong> Puedes ver las tallas de pulseras y collares y como medirlas aqui &gt;&gt; <a href=\"https:\/\/dicopebisuteria.com\/tienda\/como-elegir-tallas-de-joyas\/\">https:\/\/dicopebisuteria.com\/tienda\/como-elegir-tallas-de-joyas\/<\/a><\/p>\n<p><strong>De que materiales son las Joyitas?<\/strong> Me gusta usar cristales de Swarovski , piedras semipreciosas y rocalla de cristal japones miyuki , para el montaje me gusta trabajar con plata de ley y plata ba\u00f1ada en oro de 24kt . Las piezas mas econ\u00f3micas suelen estar montadas en cobre o lat\u00f3n ba\u00f1adas en tonos dorados, bronce o plateados<\/p>\n<p><strong>Como tengo que cuidar mis Joyitas?<\/strong> Para cuidar tus joyitas es importante saber de que material son, la plata de ley siempre debe cuidarse manteni\u00e9ndola cerrada en su bolsita de pl\u00e1stico o en una caja de pl\u00e1stico herm\u00e9tica , as\u00ed te durara a\u00f1os sin tener que limpiarla , la plata de ley ba\u00f1ada en oro o oro rosa es muy dif\u00edcil que se ponga fea , pero aun as\u00ed mantenla en un lugar seco y no la mojes con agua o perfumes amenudo! Las piezas hechas con rocallas o cristales varios siempre deben evitar mojarse de agua o perfume y las piezas hechas con metales plateados o dorados deben tener especial cuidado en esos d\u00edas calurosos , donde se suda mucho , ya que ese sudor puede deste\u00f1ir su ba\u00f1o!\u00a0 Tienes mas informaci\u00f3n aqu\u00ed &gt;&gt;&gt;<\/p>\n<p><strong>Que hago si mi joya favorita esta Agotada??<\/strong> Contactame para saber si esa joyita podr\u00e1 volver a estar disponible pronto o si realmente esta Agotada del todo! Quiz\u00e1s podr\u00eda hacerte una joyita parecida o quiz\u00e1s sea imposible :P m\u00e1ndame un chat de <strong> Whatsapp 638890244<\/strong> o contactame por correo a dicopebisuteriashop @ gmail .com <strong>(sin espacios)<\/strong><\/p>\n<p><strong>Es verdad que los cristales Swarovski se est\u00e1n Agotando en todo el mundo?<\/strong> As\u00ed es! Aunque poco se ha hablado de esto en la prensa , ya hace mas de un a\u00f1o que la marca Swarovski dejo de vender sus cristalitos a peque\u00f1os artesanos! Por eso veras en la web que algunas joyitas se agotan y no vuelven mas \ud83d\ude31 Aunque hay cristales de parecida calidad en el mercado , ya no son Swarovski, por eso en los pr\u00f3ximos meses muchas de estas joyitas se van a agotar! Por suerte yo tengo bastante stock de cristalitos en casa , pero de algunos realmente solo me queda uno \u00bfsera para ti? ;)<\/p>\n<p><strong>Tengo una tienda y me gustar\u00eda vender tus joyitas al mayor?<\/strong> Puedes acceder a la informaci\u00f3n de venta al mayor rellenando el formulario que encontraras aqu\u00ed &gt;&gt;&gt; <a href=\"https:\/\/dicopebisuteria.com\/tienda\/venta-al-mayor\/\">https:\/\/dicopebisuteria.com\/tienda\/venta-al-mayor\/<\/a>[\/vc_toggle][\/vc_column][\/vc_row][vc_row][vc_column][vc_toggle title=\u00bbSOBRE DICOPE BISUTERIA\u00bb]<strong>Quien hace las Joyitas?<\/strong> Yo misma , Diana \ud83d\ude0d hago todas las joyitas a mano en mi taller de barcelona<\/p>\n<p><strong>Que significa Dicope, de donde viene el nombre de la marca?<\/strong> Dicope son las dos primeras letras de mi nombre completo Diana Costa Pedret y es algo que cree hace mucho tiempo , cuando todav\u00eda estaba en el instituto<\/p>\n<p><strong>Que materiales usas?<\/strong> Me gusta usar cristales de Swarovski , piedras semipreciosas y rocalla de cristal japones miyuki , para el montaje me gusta trabajar con plata de ley y plata ba\u00f1ada en oro de 24kt . Las piezas mas econ\u00f3micas suelen estar montadas en cobre o lat\u00f3n ba\u00f1adas en tonos dorados, bronce o plateados<\/p>\n<p><strong>Son tus joyas realmente hechas a mano?<\/strong> Si! Todas mis joyitas son hechas a mano por mi en mi taller de Barcelona, yo creo los dise\u00f1os y realizo las piezas :) Por eso son joyas exclusivas y dif\u00edcilmente podr\u00e1s encontrarlas parecidas en otras webs.<\/p>\n<p><strong>Como puedo enterarme de Todas las Novedades y ser la primera en comprar las Rebajas?<\/strong> Puedes unirte a mi newsletter donde recibir\u00e1s las ultimas noticias de joyitas nuevas y podr\u00e1s acceder antes a los descuentos y rebajas! Adem\u00e1s tienes un 20% de descuento si te unes YA &gt;&gt; <a href=\"http:\/\/eepurl.com\/dyKvor\">http:\/\/eepurl.com\/dyKvor<\/a>[\/vc_toggle][\/vc_column][\/vc_row][vc_row][vc_column][vc_toggle title=\u00bbPEDIDOS A TU GUSTO &amp; NOVIAS\u00bb]<strong>Puedo pedir una pieza , pero en otros colores?<\/strong> Si! Claro, puedes contactarme para pedir la joyita que mas te guste en otros colores y yo te dir\u00e9 si es posible o no.<\/p>\n<p><strong>Tengo una boda o evento y necesito un tocado? Como puedo pedirlo?<\/strong> Contactame para que podamos hablar del tocado que necesitas y como lo quieres , m\u00e1ndame un chat de <strong> Whatsapp 638890244<\/strong> o contactame por correo a dicopebisuteriashop @ gmail .com <strong>(sin espacios)<\/strong><\/p>\n<p><strong>Tardaras mucho en hacer mi pedido personalizado?<\/strong> <strong>Con que antelaci\u00f3n lo pido?<\/strong> Suelo tardar unos 3 o 4 d\u00edas en hacer tu tocado o joyitas personalizadas , te recomiendo que me contactes unas tres semanas antes del evento para que te llegue seguro a tiempo \ud83d\ude0d<\/p>\n<p><strong>Se puede devolver un pedido personalizado?<\/strong> Los pedidos personalizados NO se pueden devolver! Pero no te preocupes, te mandar\u00e9 muchas fotos antes de envi\u00e1rtelo para que est\u00e9s segura de tu compra ;)<\/p>\n<p>&nbsp;<\/p>\n<h4 style=\"text-align: center;\">TIENES MAS DUDAS?<\/h4>\n<p style=\"text-align: center;\">mandame un chat de <strong> Whatsapp al 638890244<\/strong><\/p>\n<p style=\"text-align: center;\">o contactame por correo a dicopebisuteriashop @ gmail .com <strong>(sin espacios)<\/strong><\/p>\n<div class=\"woocommerce columns-4 \">        <link rel=\"stylesheet\" href=\"https:\/\/dicopebisuteria.com\/tienda\/wp-content\/themes\/xstore\/css\/modules\/woocommerce\/archive.min.css?ver=0.0.1\" type=\"text\/css\" media=\"all\" \/> \t\t<div class=\"row products products-loop products-grid row-count-4\" data-row-count=\"4\">\n\n \t<div class=\"first grid-sizer wishlist-disabled col-md-3 col-sm-6 col-xs-6 product-hover-swap product-view-disable view-color-dark et_cart-on hide-hover-on-mobile product type-product post-3139 status-publish instock product_cat-brilla product_cat-collares product_cat-collares-brilla product_cat-collares-plata product_cat-outlet has-post-thumbnail sale shipping-taxable purchasable product-type-variable\">\n        \t\t<div class=\"content-product \">\n\t\t\t\n\t\t\t\n\t\t\t\t<div class=\"product-image-wrapper hover-effect-swap\"\n                    >\n\n\t\t\t\t\t\t\t\t\t\t<p class=\"stock in-stock\">9 disponibles<\/p>                        <a class=\"product-content-image woocommerce-LoopProduct-link woocommerce-loop-product__link\" href=\"https:\/\/dicopebisuteria.com\/tienda\/producto\/collar-melissa-plata-de-ley-y-cristales-de-swarovski-dorado-y-negro\/\"\n                           data-images=\"\"\n                        >\n                            <div class=\"image-swap\"><img decoding=\"async\" width=\"555\" height=\"555\" src=\"https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/xstore\/xstore-placeholder-10x10.png\" data-src=\"https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/sparkly-jewelry-068-1-555x555.jpg\" class=\" lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" src=\"https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/xstore\/xstore-placeholder-10x10.png\" data-srcset=\"https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/sparkly-jewelry-068-1-555x555.jpg 555w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/sparkly-jewelry-068-1-100x100.jpg 100w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/sparkly-jewelry-068-1-150x150.jpg 150w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/sparkly-jewelry-068-1-300x300.jpg 300w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/sparkly-jewelry-068-1-36x36.jpg 36w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/sparkly-jewelry-068-1-32x32.jpg 32w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/sparkly-jewelry-068-1.jpg 570w\" data-sizes=\"(max-width: 555px) 100vw, 555px\" \/><\/div>\n\t<div class=\"sale-wrapper \"><span class=\"onsale type-square left\">Rebajas<\/span><\/div>\n\t<img decoding=\"async\" width=\"555\" height=\"555\" src=\"https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/Collar-Melissa-plata-de-ley-y-cristales-de-swarovski-dorado-y-negro-4-555x555.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Collar Melissa plata de ley y cristales de swarovski dorado y negro\" srcset=\"https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/Collar-Melissa-plata-de-ley-y-cristales-de-swarovski-dorado-y-negro-4-555x555.jpg 555w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/Collar-Melissa-plata-de-ley-y-cristales-de-swarovski-dorado-y-negro-4-100x100.jpg 100w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/Collar-Melissa-plata-de-ley-y-cristales-de-swarovski-dorado-y-negro-4-720x720.jpg 720w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/Collar-Melissa-plata-de-ley-y-cristales-de-swarovski-dorado-y-negro-4-150x150.jpg 150w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/Collar-Melissa-plata-de-ley-y-cristales-de-swarovski-dorado-y-negro-4-300x300.jpg 300w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/Collar-Melissa-plata-de-ley-y-cristales-de-swarovski-dorado-y-negro-4-768x768.jpg 768w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/Collar-Melissa-plata-de-ley-y-cristales-de-swarovski-dorado-y-negro-4-1024x1024.jpg 1024w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/Collar-Melissa-plata-de-ley-y-cristales-de-swarovski-dorado-y-negro-4-36x36.jpg 36w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/Collar-Melissa-plata-de-ley-y-cristales-de-swarovski-dorado-y-negro-4-32x32.jpg 32w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/Collar-Melissa-plata-de-ley-y-cristales-de-swarovski-dorado-y-negro-4.jpg 1200w\" sizes=\"(max-width: 555px) 100vw, 555px\" \/>                        <\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\t\t<div class=\"text-center product-details\">\t\t\t\t\t\t\t<h2 class=\"product-title\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/dicopebisuteria.com\/tienda\/producto\/collar-melissa-plata-de-ley-y-cristales-de-swarovski-dorado-y-negro\/\">Collar Melissa plata de ley y cristales de swarovski dorado y negro<\/a>\n                            <\/h2>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>35,00<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\">El precio original era: 35,00&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>21,00<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\">El precio actual es: 21,00&euro;.<\/span><\/span>\n\n\t\t\t\t\t\t<\/a><a href=\"https:\/\/dicopebisuteria.com\/tienda\/producto\/collar-melissa-plata-de-ley-y-cristales-de-swarovski-dorado-y-negro\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_3139\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"3139\" data-product_sku=\"\" aria-label=\"Elige las opciones para &ldquo;Collar Melissa plata de ley y cristales de swarovski dorado y negro&rdquo;\" rel=\"nofollow\" data-product_name=\"Collar Melissa plata de ley y cristales de swarovski dorado y negro\">Seleccionar opciones<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_3139\" class=\"screen-reader-text\">\n\t\tEste producto tiene m\u00faltiples variantes. Las opciones se pueden elegir en la p\u00e1gina de producto\t<\/span>\n\n                        \n                                        <\/div>\n\t\t\t\t\t\t\t\t\t         \t\t<\/div><!-- .content-product -->\n\t<\/div>\n\n \t<div class=\"wishlist-disabled col-md-3 col-sm-6 col-xs-6 product-hover-swap product-view-disable view-color-dark et_cart-on hide-hover-on-mobile product type-product post-6159 status-publish last instock product_cat-outlet product_cat-playas-de-ensueno product_cat-playas-de-ensueno-pulseras product_cat-pulsera-boho product_cat-pulseras has-post-thumbnail sale shipping-taxable purchasable product-type-variable\">\n        \t\t<div class=\"content-product \">\n\t\t\t\n\t\t\t\n\t\t\t\t<div class=\"product-image-wrapper hover-effect-swap\"\n                    >\n\n\t\t\t\t\t\t\t\t\t\t<p class=\"stock in-stock\">6 disponibles<\/p>                        <a class=\"product-content-image woocommerce-LoopProduct-link woocommerce-loop-product__link\" href=\"https:\/\/dicopebisuteria.com\/tienda\/producto\/pulsera-tropea-con-cuentas-de-cristal-marinas-azules\/\"\n                           data-images=\"\"\n                        >\n                            <div class=\"image-swap\"><img decoding=\"async\" width=\"555\" height=\"555\" src=\"https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/xstore\/xstore-placeholder-10x10.png\" data-src=\"https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/dreamy-beach-bracelets-jewelry-125-1-555x555.jpg\" class=\" lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" src=\"https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/xstore\/xstore-placeholder-10x10.png\" data-srcset=\"https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/dreamy-beach-bracelets-jewelry-125-1-555x555.jpg 555w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/dreamy-beach-bracelets-jewelry-125-1-100x100.jpg 100w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/dreamy-beach-bracelets-jewelry-125-1-720x720.jpg 720w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/dreamy-beach-bracelets-jewelry-125-1-150x150.jpg 150w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/dreamy-beach-bracelets-jewelry-125-1-300x300.jpg 300w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/dreamy-beach-bracelets-jewelry-125-1-768x768.jpg 768w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/dreamy-beach-bracelets-jewelry-125-1-1024x1024.jpg 1024w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/dreamy-beach-bracelets-jewelry-125-1-600x600.jpg 600w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/dreamy-beach-bracelets-jewelry-125-1.jpg 1200w\" data-sizes=\"(max-width: 555px) 100vw, 555px\" \/><\/div>\n\t<div class=\"sale-wrapper \"><span class=\"onsale type-square left\">Rebajas<\/span><\/div>\n\t<img decoding=\"async\" width=\"555\" height=\"555\" src=\"https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/Pulsera-Tropea-con-cuentas-de-cristal-marinas-azules-1-555x555.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Pulsera Tropea con cuentas de cristal marinas azules\" srcset=\"https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/Pulsera-Tropea-con-cuentas-de-cristal-marinas-azules-1-555x555.jpg 555w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/Pulsera-Tropea-con-cuentas-de-cristal-marinas-azules-1-100x100.jpg 100w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/Pulsera-Tropea-con-cuentas-de-cristal-marinas-azules-1-720x720.jpg 720w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/Pulsera-Tropea-con-cuentas-de-cristal-marinas-azules-1-150x150.jpg 150w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/Pulsera-Tropea-con-cuentas-de-cristal-marinas-azules-1-300x300.jpg 300w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/Pulsera-Tropea-con-cuentas-de-cristal-marinas-azules-1-768x768.jpg 768w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/Pulsera-Tropea-con-cuentas-de-cristal-marinas-azules-1-1024x1024.jpg 1024w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/Pulsera-Tropea-con-cuentas-de-cristal-marinas-azules-1-600x600.jpg 600w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/Pulsera-Tropea-con-cuentas-de-cristal-marinas-azules-1.jpg 1200w\" sizes=\"(max-width: 555px) 100vw, 555px\" \/>                        <\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\t\t<div class=\"text-center product-details\">\t\t\t\t\t\t\t<h2 class=\"product-title\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/dicopebisuteria.com\/tienda\/producto\/pulsera-tropea-con-cuentas-de-cristal-marinas-azules\/\">Pulsera Tropea con cuentas de cristal marinas azules<\/a>\n                            <\/h2>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>10,00<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\">El precio original era: 10,00&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>6,00<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\">El precio actual es: 6,00&euro;.<\/span><\/span>\n\n\t\t\t\t\t\t<\/a><a href=\"https:\/\/dicopebisuteria.com\/tienda\/producto\/pulsera-tropea-con-cuentas-de-cristal-marinas-azules\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_6159\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"6159\" data-product_sku=\"\" aria-label=\"Elige las opciones para &ldquo;Pulsera Tropea con cuentas de cristal marinas azules&rdquo;\" rel=\"nofollow\" data-product_name=\"Pulsera Tropea con cuentas de cristal marinas azules\">Seleccionar opciones<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_6159\" class=\"screen-reader-text\">\n\t\tEste producto tiene m\u00faltiples variantes. Las opciones se pueden elegir en la p\u00e1gina de producto\t<\/span>\n\n                        \n                                        <\/div>\n\t\t\t\t\t\t\t\t\t         \t\t<\/div><!-- .content-product -->\n\t<\/div>\n\n \t<div class=\"first grid-sizer wishlist-disabled col-md-3 col-sm-6 col-xs-6 product-hover-swap product-view-disable view-color-dark et_cart-on hide-hover-on-mobile product type-product post-616 status-publish instock product_cat-dicope-joyas product_cat-dicope-joyas-pendientes product_cat-outlet product_cat-pendientes product_cat-pendientes-boho has-post-thumbnail sale shipping-taxable purchasable product-type-simple\">\n        \t\t<div class=\"content-product \">\n\t\t\t\n\t\t\t\n\t\t\t\t<div class=\"product-image-wrapper hover-effect-swap\"\n                    >\n\n\t\t\t\t\t\t\t\t\t\t<p class=\"stock in-stock\">1 disponibles<\/p>                        <a class=\"product-content-image woocommerce-LoopProduct-link woocommerce-loop-product__link\" href=\"https:\/\/dicopebisuteria.com\/tienda\/producto\/pendientes-flora-rosa-y-ruby-cuentas-cristal\/\"\n                           data-images=\"\"\n                        >\n                            <div class=\"image-swap\"><img decoding=\"async\" width=\"555\" height=\"555\" src=\"https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/xstore\/xstore-placeholder-10x10.png\" data-src=\"https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/pendientes-flora-abaloriosrosa-y-ruby-555x555.jpg\" class=\" lazyload lazyload-simple et-lazyload-fadeIn\" alt=\"\" src=\"https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/xstore\/xstore-placeholder-10x10.png\" data-srcset=\"https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/pendientes-flora-abaloriosrosa-y-ruby-555x555.jpg 555w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/pendientes-flora-abaloriosrosa-y-ruby-100x100.jpg 100w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/pendientes-flora-abaloriosrosa-y-ruby-150x150.jpg 150w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/pendientes-flora-abaloriosrosa-y-ruby-300x300.jpg 300w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/pendientes-flora-abaloriosrosa-y-ruby-36x36.jpg 36w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/pendientes-flora-abaloriosrosa-y-ruby-32x32.jpg 32w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/pendientes-flora-abaloriosrosa-y-ruby.jpg 570w\" data-sizes=\"(max-width: 555px) 100vw, 555px\" \/><\/div>\n\t<div class=\"sale-wrapper \"><span class=\"onsale type-square left with-percentage\">Rebajas 52%<\/span><\/div>\n\t<img decoding=\"async\" width=\"555\" height=\"555\" src=\"https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/pendientes-flora-rosa-y-ruby-555x555.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Pendientes Flora Rosa y Ruby cuentas cristal\" srcset=\"https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/pendientes-flora-rosa-y-ruby-555x555.jpg 555w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/pendientes-flora-rosa-y-ruby-100x100.jpg 100w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/pendientes-flora-rosa-y-ruby-150x150.jpg 150w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/pendientes-flora-rosa-y-ruby-300x300.jpg 300w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/pendientes-flora-rosa-y-ruby-36x36.jpg 36w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/pendientes-flora-rosa-y-ruby-32x32.jpg 32w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/pendientes-flora-rosa-y-ruby.jpg 570w\" sizes=\"(max-width: 555px) 100vw, 555px\" \/>                        <\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\t\t<div class=\"text-center product-details\">\t\t\t\t\t\t\t<h2 class=\"product-title\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/dicopebisuteria.com\/tienda\/producto\/pendientes-flora-rosa-y-ruby-cuentas-cristal\/\">Pendientes Flora Rosa y Ruby cuentas cristal<\/a>\n                            <\/h2>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>50,00<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\">El precio original era: 50,00&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>24,00<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\">El precio actual es: 24,00&euro;.<\/span><\/span>\n\n\t\t\t\t\t\t<\/a><a href=\"\/tienda\/wp-json\/wp\/v2\/pages\/8254?add-to-cart=616\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_616\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"616\" data-product_sku=\"\" aria-label=\"A\u00f1adir al carrito: &ldquo;Pendientes Flora Rosa y Ruby cuentas cristal&rdquo;\" rel=\"nofollow\" data-success_message=\"\u00abPendientes Flora Rosa y Ruby cuentas cristal\u00bb se ha a\u00f1adido a tu carrito\" data-product_name=\"Pendientes Flora Rosa y Ruby cuentas cristal\" role=\"button\">A\u00f1adir al carrito<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_616\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\n                        \n                                        <\/div>\n\t\t\t\t\t\t\t\t\t         \t\t<\/div><!-- .content-product -->\n\t<\/div>\n\n \t<div class=\"wishlist-disabled col-md-3 col-sm-6 col-xs-6 product-hover-swap product-view-disable view-color-dark et_cart-on hide-hover-on-mobile product type-product post-633 status-publish last outofstock product_cat-dicope-joyas product_cat-outlet product_cat-pulsera-boho product_cat-pulseras has-post-thumbnail sale shipping-taxable purchasable product-type-simple\">\n        \t\t<div class=\"content-product \">\n\t\t\t\n\t\t\t\n\t\t\t\t<div class=\"product-image-wrapper hover-effect-swap\"\n                    >\n\n\t\t\t\t\t\t\t\t\t\t<p class=\"stock out-of-stock\">Sin existencias<\/p>                        <a class=\"product-content-image woocommerce-LoopProduct-link woocommerce-loop-product__link\" href=\"https:\/\/dicopebisuteria.com\/tienda\/producto\/pulsera-corazon-perlas-y-bolitas-cristal-marron\/\"\n                           data-images=\"\"\n                        >\n                            \n\t<div class=\"sale-wrapper \"><span class=\"onsale type-square left with-percentage\">Rebajas 53%<\/span><\/div>\n\t<img decoding=\"async\" width=\"555\" height=\"555\" src=\"https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/pulsera-corazon-perlas-y-bolitas-cristal-marron-555x555.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Pulsera Coraz\u00f3n Perlas y Bolitas Cristal Marr\u00f3n\" srcset=\"https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/pulsera-corazon-perlas-y-bolitas-cristal-marron-555x555.jpg 555w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/pulsera-corazon-perlas-y-bolitas-cristal-marron-100x100.jpg 100w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/pulsera-corazon-perlas-y-bolitas-cristal-marron-150x150.jpg 150w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/pulsera-corazon-perlas-y-bolitas-cristal-marron-300x300.jpg 300w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/pulsera-corazon-perlas-y-bolitas-cristal-marron-36x36.jpg 36w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/pulsera-corazon-perlas-y-bolitas-cristal-marron-32x32.jpg 32w, https:\/\/dicopebisuteria.com\/tienda\/wp-content\/uploads\/pulsera-corazon-perlas-y-bolitas-cristal-marron.jpg 570w\" sizes=\"(max-width: 555px) 100vw, 555px\" \/>                        <\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t\t\t<div class=\"text-center product-details\">\t\t\t\t\t\t\t<h2 class=\"product-title\">\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/dicopebisuteria.com\/tienda\/producto\/pulsera-corazon-perlas-y-bolitas-cristal-marron\/\">Pulsera Coraz\u00f3n Perlas y Bolitas Cristal Marr\u00f3n<\/a>\n                            <\/h2>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>15,00<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\">El precio original era: 15,00&euro;.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>7,00<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\">El precio actual es: 7,00&euro;.<\/span><\/span>\n\n\t\t\t\t\t\t<\/a><a href=\"https:\/\/dicopebisuteria.com\/tienda\/producto\/pulsera-corazon-perlas-y-bolitas-cristal-marron\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_633\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"633\" data-product_sku=\"\" aria-label=\"Lee m\u00e1s sobre &ldquo;Pulsera Coraz\u00f3n Perlas y Bolitas Cristal Marr\u00f3n&rdquo;\" rel=\"nofollow\" data-success_message=\"\" data-product_name=\"Pulsera Coraz\u00f3n Perlas y Bolitas Cristal Marr\u00f3n\">Leer m\u00e1s<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_633\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\n                        \n                                        <\/div>\n\t\t\t\t\t\t\t\t\t         \t\t<\/div><!-- .content-product -->\n\t<\/div>\n\n<\/div> <!-- .row --><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; PREGUNTAS FRECUENTES &nbsp; Bienvenida a Dicope Bisuter\u00eda Preciosa! Encuentra Bisuter\u00eda Artesanal creada personalmente en mi taller de Barcelona &nbsp; \u00a0INFORMACION MI CUENTA \/ LOG&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8254","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/dicopebisuteria.com\/tienda\/wp-json\/wp\/v2\/pages\/8254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicopebisuteria.com\/tienda\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dicopebisuteria.com\/tienda\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dicopebisuteria.com\/tienda\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicopebisuteria.com\/tienda\/wp-json\/wp\/v2\/comments?post=8254"}],"version-history":[{"count":45,"href":"https:\/\/dicopebisuteria.com\/tienda\/wp-json\/wp\/v2\/pages\/8254\/revisions"}],"predecessor-version":[{"id":8666,"href":"https:\/\/dicopebisuteria.com\/tienda\/wp-json\/wp\/v2\/pages\/8254\/revisions\/8666"}],"wp:attachment":[{"href":"https:\/\/dicopebisuteria.com\/tienda\/wp-json\/wp\/v2\/media?parent=8254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}